{"id":87,"count":3,"description":"","link":"https:\/\/www.nekson.co\/fr\/category\/design-fr\/","name":"Design","slug":"design-fr","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Design Archives - NEKSON \/ Montreal Digital | Design | Marketing Agency<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Design Archives - NEKSON \/ Montreal Digital | Design | Marketing Agency\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.nekson.co\/fr\/category\/design-fr\/\" \/>\n<meta property=\"og:site_name\" content=\"NEKSON \/ Montreal Digital | Design | Marketing Agency\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@realnekson\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.nekson.co\\\/fr\\\/category\\\/design-fr\\\/\",\"url\":\"https:\\\/\\\/www.nekson.co\\\/fr\\\/category\\\/design-fr\\\/\",\"name\":\"Design Archives - NEKSON \\\/ Montreal Digital | Design | Marketing Agency\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.nekson.co\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.nekson.co\\\/fr\\\/category\\\/design-fr\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.nekson.co\\\/fr\\\/category\\\/design-fr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.nekson.co\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Design\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.nekson.co\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.nekson.co\\\/fr\\\/\",\"name\":\"NEKSON \\\/ Montreal Digital | Design | Marketing Agency\",\"description\":\"Best montreal design agency specialized in web, brand identity, logo and ecommerce\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.nekson.co\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Design Archives - NEKSON \/ Montreal Digital | Design | Marketing Agency","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Design Archives - NEKSON \/ Montreal Digital | Design | Marketing Agency","og_url":"https:\/\/www.nekson.co\/fr\/category\/design-fr\/","og_site_name":"NEKSON \/ Montreal Digital | Design | Marketing Agency","twitter_card":"summary_large_image","twitter_site":"@realnekson","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.nekson.co\/fr\/category\/design-fr\/","url":"https:\/\/www.nekson.co\/fr\/category\/design-fr\/","name":"Design Archives - NEKSON \/ Montreal Digital | Design | Marketing Agency","isPartOf":{"@id":"https:\/\/www.nekson.co\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/www.nekson.co\/fr\/category\/design-fr\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.nekson.co\/fr\/category\/design-fr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.nekson.co\/fr\/"},{"@type":"ListItem","position":2,"name":"Design"}]},{"@type":"WebSite","@id":"https:\/\/www.nekson.co\/fr\/#website","url":"https:\/\/www.nekson.co\/fr\/","name":"NEKSON \/ Montreal Digital | Design | Marketing Agency","description":"Best montreal design agency specialized in web, brand identity, logo and ecommerce","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.nekson.co\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.nekson.co\/fr\/wp-json\/wp\/v2\/categories\/87","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nekson.co\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.nekson.co\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.nekson.co\/fr\/wp-json\/wp\/v2\/posts?categories=87"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}